{"id":656,"date":"2019-11-04T14:09:40","date_gmt":"2019-11-04T14:09:40","guid":{"rendered":"https:\/\/mutti-parma.com\/de\/recipe\/gekuehlte-sommersuppe-mit-jakobsmuscheln\/"},"modified":"2026-04-22T14:01:19","modified_gmt":"2026-04-22T14:01:19","slug":"gekuehlte-sommersuppe-mit-jakobsmuscheln","status":"publish","type":"recipe","link":"https:\/\/mutti-parma.com\/de\/tomatenrezepte\/gekuehlte-sommersuppe-mit-jakobsmuscheln\/","title":{"rendered":"Sommersuppe mit Jakobsmuscheln"},"content":{"rendered":"\n<p>Diese gek\u00fchlte Sommersuppe mit Jakobsmuscheln ist die perfekte Kombination aus mediterraner Leichtigkeit und feiner Eleganz. Fruchtiges Tomatenfruchtfleisch trifft auf frisches Gem\u00fcse und wird mit zart gebratenen Jakobsmuscheln veredelt. Ideal f\u00fcr warme Tage, \u00fcberzeugt dieses Rezept mit seiner erfrischenden Textur und seinem ausgewogenen Geschmack \u2013 schnell zubereitet und perfekt als leichte Vorspeise oder raffiniertes Sommergericht.<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Diese gek\u00fchlte Sommersuppe mit Jakobsmuscheln ist die perfekte Kombination aus mediterraner Leichtigkeit und feiner Eleganz. Fruchtiges Tomatenfruchtfleisch trifft auf frisches Gem\u00fcse und wird mit zart gebratenen Jakobsmuscheln veredelt. Ideal f\u00fcr warme Tage, \u00fcberzeugt dieses Rezept mit seiner erfrischenden Textur und seinem ausgewogenen Geschmack \u2013 schnell zubereitet und perfekt als leichte Vorspeise oder raffiniertes Sommergericht.<\/p>\n","protected":false},"author":1,"featured_media":657,"comment_status":"open","ping_status":"open","template":"","ingredient":[216,390,389,240,85,110,391,140,99,114,109],"course":[17,20],"cuisine":[25],"difficulty":[76],"diet":[31,32,29],"occasion":[35,36,38],"dish":[42,43],"cooking_time":[],"class_list":["post-656","recipe","type-recipe","status-publish","has-post-thumbnail","hentry","ingredient-fruehlingszwiebel","ingredient-gurke","ingredient-jakobsmuscheln","ingredient-kapern","ingredient-mutti-feinstes-tomatenfruchtfleisch","ingredient-pfeffer","ingredient-radicchio","ingredient-rote-paprikaschote","ingredient-salz","ingredient-semmelbroesel","ingredient-oel","course-vorspeisen","course-hauptgerichte","cuisine-italienische-kueche","difficulty-einfach","diet-gesunde-kueche","diet-laktosefrei","diet-glutenfrei","occasion-schnell-und-lecker","occasion-essen-mit-freunden","occasion-fuer-die-ganze-familie","dish-tomatensuppe","dish-fisch","rating-0-stars","post","type-post"],"acf":[],"_links":{"self":[{"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/recipe\/656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/recipe"}],"about":[{"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/types\/recipe"}],"author":[{"embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/comments?post=656"}],"version-history":[{"count":9,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/recipe\/656\/revisions"}],"predecessor-version":[{"id":9050,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/recipe\/656\/revisions\/9050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/media\/657"}],"wp:attachment":[{"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/media?parent=656"}],"wp:term":[{"taxonomy":"ingredient","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/ingredient?post=656"},{"taxonomy":"course","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/course?post=656"},{"taxonomy":"cuisine","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/cuisine?post=656"},{"taxonomy":"difficulty","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/difficulty?post=656"},{"taxonomy":"diet","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/diet?post=656"},{"taxonomy":"occasion","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/occasion?post=656"},{"taxonomy":"dish","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/dish?post=656"},{"taxonomy":"cooking_time","embeddable":true,"href":"https:\/\/mutti-parma.com\/de\/wp-json\/wp\/v2\/cooking_time?post=656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}